{"id":2268,"date":"2025-04-18T18:54:17","date_gmt":"2025-04-18T16:54:17","guid":{"rendered":"https:\/\/optimizarwordpress.net\/burrotrek\/route\/4-6-tage-in-den-bergdoerfern-und-seen\/"},"modified":"2026-04-08T09:41:59","modified_gmt":"2026-04-08T07:41:59","slug":"4-6-tage-in-den-bergdoerfern-und-seen","status":"publish","type":"route","link":"https:\/\/burrotrek.com\/de\/route\/4-6-tage-in-den-bergdoerfern-und-seen\/","title":{"rendered":"4-6 Tage zu den Bergd\u00f6rfern und Seen"},"featured_media":2273,"template":"","best-season":[102],"camp-setup":[86],"difficulty-level":[78],"trail-length":[66],"trek-style":[50],"class_list":["post-2268","route","type-route","status-publish","has-post-thumbnail","hentry","best-season-sommer","camp-setup-unterkunft","difficulty-level-mittel","trail-length-mehrere-tage","trek-style-selbstgefuehrt"],"meta_box":{"available_activities":"Eine gem\u00fctliche Tour mit \u00dcbernachtungen in Unterk\u00fcnften","starting_from":"Cal Jan (Pyren\u00e4en)","route_intro_text":"Eselwanderung durch die Pyren\u00e4en \u2013 Ein familienfreundliches Abenteuer","route_gallery":[{"images":"1029"},{"images":"1413"},{"images":"1588"}],"route_location":"Cal Jan de la Llosa - Refugi Cap de Rec - Refugi Estanys de la Pera -Andorra- Aransa -Lles -Cal Jan de la Llosa","route_description":"<p data-start=\"475\" data-end=\"812\">Diese Rundwanderung f\u00fchrt dich zusammen mit deinem <strong data-start=\"591\" data-end=\"621\">treuen Eselgef\u00e4hrten<\/strong> durch das ruhige <strong data-start=\"644\" data-end=\"660\">Llosa-Tal<\/strong> und die charmanten Bergd\u00f6rfer <strong data-start=\"699\" data-end=\"711\">Viliella<\/strong>, <strong data-start=\"713\" data-end=\"724\">Aranser<\/strong>, <strong data-start=\"726\" data-end=\"736\">Musser<\/strong> und <strong data-start=\"742\" data-end=\"762\">Lles de Cerdanya<\/strong>. Unterwegs wanderst du durch blumenreiche Wiesen, schattige W\u00e4lder und vorbei an einem kleinen Wasserfall, bevor du den wundersch\u00f6nen Bergsee Estany de <strong data-start=\"798\" data-end=\"809\">La Pera<\/strong> erreichst.<\/p>\n<p data-start=\"814\" data-end=\"1158\">Die komplette Rundwanderung dauert <strong data-start=\"837\" data-end=\"849\">sechs Tage<\/strong>, kann aber leicht auf <strong data-start=\"885\" data-end=\"901\">vier oder f\u00fcnf<\/strong> verk\u00fcrzt werden. Mit t\u00e4glichen Etappen von etwa <strong data-start=\"931\" data-end=\"940\">10 km<\/strong> ist diese Tour perfekt f\u00fcr Familien mit kleinen Kindern oder alle, die die Berge in entspanntem Tempo genie\u00dfen m\u00f6chten. Du kannst sogar einen <strong data-start=\"1078\" data-end=\"1090\">Ruhetag<\/strong> einlegen, um einfach zu entspannen und die Ruhe und Sch\u00f6nheit der Pyren\u00e4en aufzusaugen.<\/p>\n<p data-start=\"1160\" data-end=\"1383\">Unterk\u00fcnfte sind in <strong data-start=\"1195\" data-end=\"1212\">gem\u00fctlichen Bergh\u00fctten<\/strong> und <strong data-start=\"1217\" data-end=\"1228\">Hostels<\/strong> entlang des Weges verf\u00fcgbar.<\/p>\n<p class=\"\" data-start=\"1445\" data-end=\"1584\">\n","technical_data_sheet":[],"route_price_note":"Bitte sehe den Preisbereich auf unserer Website f\u00fcr Eselmietpreise an, wo auch Informationen zu finden sind, wie die Touren organisiert sind.","multi_day":"1","switch_startingpoint":"1","route_detail":[{"day":"Tag 1  ","description_multi_day":"<strong data-start=\"1420\" data-end=\"1470\">Cal Jan de la Llosa \u2192 Refugi Cap de Rec<\/strong>\r\n\r\n<strong>Entfernung:<\/strong> 9 km\r\n\r\n<strong>H\u00f6he:<\/strong> -259 \/+ 595\r\n\r\n<br data-start=\"1470\" data-end=\"1473\" \/>Dein Abenteuer beginnt im friedlichen Llosa-Tal, wo der Weg sanft durch Kiefernw\u00e4lder und Bergweiden f\u00fchrt. Unterwegs kan man ein kurzer Abstecher zum <strong data-start=\"1644\" data-end=\"1661\">Salt del Mol\u00ed<\/strong>, einem erfrischenden Wasserfall im Wald machen \u2013 der perfekte Ort f\u00fcr ein Picknick oder ein Bad an einem warmen Tag. Beim Aufstieg \u00f6ffnen sich die Ausblicke zu den umliegenden Berggipfeln, bevor man das<strong data-start=\"1839\" data-end=\"1860\"> Refugi Cap de Rec<\/strong> erreicht, eine freundliche Bergh\u00fctte, umgeben von offenen Alpenwiesen.","starting_point_media_multi_day":"1026"},{"day":"Tag 2","description_multi_day":"<strong data-start=\"1924\" data-end=\"1965\">Cap de Rec \u2192 Refugi de la Pera<\/strong>\r\n\r\n<strong>Entfernung:<\/strong> 9,14 km\r\n\r\n<strong>H\u00f6henunterschied:<\/strong> - 207\/+ 605\r\n\r\n<br data-start=\"1965\" data-end=\"1968\" \/>Der heutige Weg schl\u00e4ngelt sich nach oben durch W\u00e4lder und \u00fcber Wiesen. Je h\u00f6her man kommt, desto imposanter wird die Aussicht auf die beeindruckende <strong data-start=\"2131\" data-end=\"2149\">Serra del Cad\u00ed<\/strong>, deren Berggipfel stolz gegen den Himmel ragen. Das <strong data-start=\"2198\" data-end=\"2219\">Refugi de la Pera<\/strong> wartet direkt oberhalb der Baumgrenze neben zwei schimmernden blauen Seen \u2013 ein idyllischer Ort, um die Nacht zu verbringen, Murmeltiere spielen zu sehen und dein Esel in der N\u00e4he zu beobachten.","starting_point_media_multi_day":"1596"},{"day":"Tag 3  ","description_multi_day":"<strong>Tageswanderung nach Andorra<\/strong>\r\n\r\n<strong>Entfernung:<\/strong> 10 km\r\n\r\n<strong>H\u00f6he:<\/strong> +\/-656\r\n\r\nVon der Bergh\u00fctte aus kann man eine spektakul\u00e4re Tageswanderung \u00fcber den <strong data-start=\"2510\" data-end=\"2530\">Port de Perafita-Pass<\/strong> nach <strong data-start=\"2541\" data-end=\"2552\">Andorra<\/strong> unternehmen. Der Weg steigt steil zwischen Granitgipfeln hoch und f\u00fchrt zum <strong data-start=\"2616\" data-end=\"2638\">Refugi de Perafita<\/strong> und <strong data-start=\"2643\" data-end=\"2663\">Estany de Claror,<\/strong> der als <em data-start=\"2680\" data-end=\"2714\">w\u00e4rmster Bergsee Andorras<\/em> gilt. Hier, umgeben von Stille und weiten Ausblicken, f\u00fchlt man sich fern vom Alltag und der Zivilisation. Danach geht die Wanderung zur\u00fcck zum Refugi de la Pera, wo man einen weiteren gem\u00fctlichen Abend nahe den Sternen verbringt.\r\n\r\n<br data-start=\"2829\" data-end=\"2832\" \/><em data-start=\"2835\" data-end=\"2978\">Diese Etappe kannst du auch \u00fcberspringen, wenn du m\u00f6chtest \u2013 oder du kannst einfach einen entspannten Ruhetag im Refugi de la Pera einlegen, um die Berglandschaft zu genie\u00dfen.<\/em>","starting_point_media_multi_day":"1588"},{"day":"Tag 4","description_multi_day":"<strong data-start=\"2872\" data-end=\"2910\">Refugi de la Pera \u2192 Aranser<\/strong>\r\n\r\n<strong>Entfernung:<\/strong> 9,5 km\r\n\r\n<strong>H\u00f6he:<\/strong> - 1007\/ + 107\r\n\r\nDer Abstieg von La Pera ist ein Genuss \u2013 durch duftende <strong data-start=\"2970\" data-end=\"2986\">Kiefernw\u00e4lder<\/strong>, vorbei an einem kleinen See und hinunter in <strong data-start=\"3040\" data-end=\"3065\">blumenreiche Wiesen.<\/strong> Der Weg f\u00fchrt dich sanft zum ruhigen Dorf <strong data-start=\"3117\" data-end=\"3128\">Aranser<\/strong>, wo Steinh\u00e4user und enge Gassen dich zum Verweilen einladen. Genie\u00dfe ein herzhaftes Abendessen und vielleicht ein Glas lokaler Wein, w\u00e4hrend man das Abendlicht \u00fcber das Tal fallen sieht.","starting_point_media_multi_day":"1597"},{"day":"Tag 5","description_multi_day":"<strong data-start=\"3304\" data-end=\"3340\">Aranser \u2192 Lles \u00fcber Musser<\/strong>\r\n\r\n<strong>Entfernung<\/strong>: 9 km\r\n\r\n<b>H\u00f6he:<\/b> - 797\/ +325\r\n\r\n<br data-start=\"3340\" data-end=\"3343\" \/>Ein wundersch\u00f6ner Verbindungsweg f\u00fchrt durch <strong data-start=\"3390\" data-end=\"3400\">Musser<\/strong>, ein weiteres authentisches pyren\u00e4isches Bergdorf mit traditionellen Schieferd\u00e4chern und friedlichem Charme. Die Wanderung f\u00fchrt \u00fcber eine alte Br\u00fccke den <strong data-start=\"3517\" data-end=\"3536\">Pont del Diablo<\/strong> \u2013 der \"Teufelsbr\u00fccke\" \u2013 und geht dann durch gemischte W\u00e4lder und offene Felder, bis Sie <strong data-start=\"3644\" data-end=\"3664\">Lles de Cerdanya<\/strong>, ein lebendiges Bergdorf mit freundlicher Atmosph\u00e4re.\r\n\r\n<em>Wenn Du eine k\u00fcrzere Strecke bevorzugst, kannst Du diese Etappe \u00fcberspringen \u2013 gehen einfach direkt von Aranser zur\u00fcck nach Cal Jan de la Llosa (7km).<\/em>","starting_point_media_multi_day":"714"},{"day":"Tag 6","description_multi_day":"<strong>Lles \u2192 Viliella \u2192 Cal Jan de la Llosa<\/strong>\r\n\r\n<strong>Entfernung:<\/strong> 6,6 km\r\n\r\n<strong>H\u00f6henunterschied:<\/strong> +213\/-356\r\n\r\nDer letzte Tag f\u00fchrt \u00fcber Bergwiesen Wiesen und entlang kleiner, gewundener Wege zum malerischen Berdorf <strong data-start=\"4134\" data-end=\"4146\">Viliella<\/strong>. Von dort kommt man wieder ins Llosa-Tal und zur\u00fcck nach Cal Jan de la Llosa, wo die Reise begann. In der erfrischenden Llosa hat man nochmals die M\u00f6glichkeit ein Bad zu nehmen, w\u00e4hrend die Esel friedlich an frischen Bergkr\u00e4utern knabbern.\r\n\r\nDies ist ein perfekter Moment, um <strong data-start=\"657\" data-end=\"702\">langsam von deinen Eselsfreunden Abschied zu nehmen<\/strong>, die alle Abenteuer und die sch\u00f6nen Berge mit dir geteilt haben","starting_point_media_multi_day":"1579"}],"starting_point_media":false,"description_starting_point":["<p>Cal Jan de la Llosa \u2013 25726 Viliella<\/p>\n<p>Cal Jan de la Llosa ist ein<i> Masia (Bauernhaus<\/i> ) etwa 3 km vom kleinen Dorf Viliella entfernt. Die Hausbesitzer bieten Wanderern die M\u00f6glichkeit, mit ihrem eigenen Zelt auf der Wiese zu zelten. (Keine Infrastruktur). Die Kosten f\u00fcr die Nacht im Zelt betragen 15 \u20ac pro Nacht und Zelt.<\/p>\n<p>Die n\u00e4chste Unterkunft befindet sich im Dorf <em>Lles de Cerdanya<\/em>. Wenn Ihr mit \u00f6ffentlichen Verkehrsmitteln anreist und kein Zelt dabei habt, empfehlen wir, die Nacht vorher im Tal (Bellver de Cerdanya oder Martinet) zu \u00fcbernachten und am Tag der Eselwanderung direkt mit einem Taxi zu uns zu fahren.<\/p>\n"],"relevant_information":"<ul>\n<li data-start=\"186\" data-end=\"535\">\n<p data-start=\"188\" data-end=\"208\"><strong data-start=\"188\" data-end=\"206\">Unterkunft:<\/strong><\/p>\n<ul data-start=\"211\" data-end=\"535\">\n<li data-start=\"211\" data-end=\"372\">\n<p data-start=\"213\" data-end=\"372\"><strong data-start=\"213\" data-end=\"255\">Refugi de la Pera (Estany de la Pera):<\/strong> Du musst einen <strong data-start=\"276\" data-end=\"303\">Schlafsack oder eine Decke<\/strong> mitbringen. Es ist auch m\u00f6glich, <strong data-start=\"332\" data-end=\"345\">Bettw\u00e4sche<\/strong> im Voraus zu reservieren.<\/p>\n<\/li>\n<li data-start=\"375\" data-end=\"457\">\n<p data-start=\"377\" data-end=\"457\"><strong data-start=\"377\" data-end=\"399\">Refugi Cap de Rec:<\/strong> Familienzimmer m\u00fcssen gebucht werden, wenn man ein privates Zimmer m\u00f6chte.<\/p>\n<\/li>\n<li data-start=\"460\" data-end=\"535\">\n<p data-start=\"462\" data-end=\"535\"><strong data-start=\"462\" data-end=\"484\">Alle Unterk\u00fcnfte<\/strong> bieten <strong data-start=\"491\" data-end=\"505\">Vollverpflegung<\/strong> und <strong data-start=\"510\" data-end=\"521\">Picknicks<\/strong> auf Anfrage.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li data-start=\"537\" data-end=\"753\">\n<p data-start=\"539\" data-end=\"609\"><strong data-start=\"539\" data-end=\"548\">Hunde:<\/strong> Hunde sind willkommen, aber sie <strong data-start=\"576\" data-end=\"606\">k\u00f6nnen nicht in Schlafs\u00e4len bleiben<\/strong>.<\/p>\n<ul data-start=\"612\" data-end=\"753\">\n<li data-start=\"612\" data-end=\"678\">\n<p data-start=\"614\" data-end=\"678\">Im <strong data-start=\"617\" data-end=\"638\">Refugi Cap de Rec<\/strong> buche\u00a0 ein <strong data-start=\"647\" data-end=\"662\">Familienzimmer<\/strong> wenn du deinen Hund mitbringst.<\/p>\n<\/li>\n<li data-start=\"681\" data-end=\"753\">\n<p data-start=\"683\" data-end=\"753\"><strong data-start=\"686\" data-end=\"707\">In Estany de la Pera<\/strong> m\u00fcssen die Hunde <strong data-start=\"719\" data-end=\"750\">au\u00dferhalb des Schlafsaals schlafen<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li data-start=\"755\" data-end=\"1071\">\n<p data-start=\"757\" data-end=\"784\"><strong data-start=\"757\" data-end=\"782\">Ausr\u00fcstung &amp; Kleidung:<\/strong><\/p>\n<ul data-start=\"787\" data-end=\"1071\">\n<li data-start=\"787\" data-end=\"889\">\n<p data-start=\"789\" data-end=\"889\"><strong data-start=\"789\" data-end=\"805\">Wanderschuhe<\/strong> werden dringend empfohlen \u2013 entlang der Route gibt es viele Fl\u00fcsse und steinige Wege.<\/p>\n<\/li>\n<li data-start=\"892\" data-end=\"995\">\n<p data-start=\"894\" data-end=\"995\">Bringe <strong data-start=\"900\" data-end=\"918\">Sonnenschutz<\/strong>, <strong data-start=\"920\" data-end=\"948\">wasserabweisende Kleidung<\/strong> und Kleidung im Schichtenprinzip f\u00fcr wechselnde Wetterbedingungen mit.<\/p>\n<\/li>\n<li data-start=\"998\" data-end=\"1071\">\n<p data-start=\"1000\" data-end=\"1071\"><strong data-start=\"1000\" data-end=\"1017\">Reichlich Wasserflaschen<\/strong>\u00a0sind f\u00fcr Tageswanderungen unerl\u00e4sslich.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li data-start=\"1073\" data-end=\"1245\">\n<p data-start=\"1075\" data-end=\"1095\"><strong data-start=\"1075\" data-end=\"1093\">Essen &amp; Snacks:<\/strong><\/p>\n<ul data-start=\"1098\" data-end=\"1245\">\n<li data-start=\"1098\" data-end=\"1174\">\n<p data-start=\"1100\" data-end=\"1174\"><strong data-start=\"1110\" data-end=\"1138\">Entlang der Route gibt es keine Gesch\u00e4fte<\/strong>, also bringe <strong data-start=\"1149\" data-end=\"1159\">Snacks<\/strong> f\u00fcr den Tag mit.<\/p>\n<\/li>\n<li data-start=\"1177\" data-end=\"1245\">\n<p data-start=\"1179\" data-end=\"1245\">Picknicks k\u00f6nnen im Voraus in den Unterk\u00fcnften organisiert werden.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li data-start=\"1247\" data-end=\"1483\">\n<p data-start=\"1249\" data-end=\"1266\"><strong data-start=\"1249\" data-end=\"1264\">Weitere Tipps:<\/strong><\/p>\n<ul data-start=\"1269\" data-end=\"1483\">\n<li data-start=\"1269\" data-end=\"1373\">\n<p data-start=\"1271\" data-end=\"1373\">Optional k\u00f6nnt ihr unterwegs <strong data-start=\"1284\" data-end=\"1297\">Ruhetage<\/strong> einplanen und die wundersch\u00f6ne Berglandschaft mit den Eseln ganz gem\u00fctlich genie\u00dfen.<\/p>\n<\/li>\n<li data-start=\"1376\" data-end=\"1483\">\n<p data-start=\"1378\" data-end=\"1483\">\u00dcberpr\u00fcfe im Voraus das Wetter und passe die Ausr\u00fcstung entsprechend an \u2013 die Bergbedingungen k\u00f6nnen sich schnell \u00e4ndern.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","route":[{"location":"\u26b2 Cal Jan de la Llosa \/ \u26b2 Refugi Cap de Rec \/ \u26b2 Refugi Estany de la Pera \/ \u26b2 Andorra \/ \u26b2 Aransa \/ \u26b2 Lles"}],"starting_point_coordinates":"Cal Jan de la Llosa \u2013 Lles de Cerdanya","starting_point_coordinates_label":"42\u00b026'22,65\"N\/1\u00b041'58,28\"O","starting_point_name":"Cal Jan de la Llosa \u2013 Lles de Cerdanya","how_to_arrive_public_transport":"<p>Mit dem Zug von Perpignan oder Barcelona<a href=\"http:\/\/www.renfe.com\/viajeros\/cercanias\/barcelona\/index.html\"> (RENFE)<\/a> nach Puigcerd\u00e0 und dann mit <a href=\"https:\/\/www.alsa.es\/en\/home\">dem Bus (Alsa<\/a> oder <a href=\"http:\/\/www.horarios.info\/buscar\/horario-transporte\">Horarios<\/a>) nach Martinet. Von Martinet mit dem Taxi nach Cal Jan de la Llosa.<\/p>\n<p>Oder ein Direktbus von Barcelona oder Girona, zuerst nach Puigcerd\u00e0 oder direkt nach Martinet (je nach Anschluss).<\/p>\n<p>Taxi Sala: 0034 973 515 054 \/ 0034 646 331 744<\/p>\n","how_to_arrive_by_private_car":"<p>Von der K\u00fcste (Perpignan, Figueres, Girona, Barcelona) zuerst in Richtung Andorra. Vor Andorra, 25 km nach Puigcerda auf der N260 in Prullans oder Martinet, biegen Sie in Richtung Lles de Cerdanya ab.<\/p>\n<p>Auf der LV-4036 etwa 10 km bis Lles und dann weiter nach Viliella<\/p>\n<p>In Viliella gibt es eine 3 km lange Schotterstra\u00dfe nach Cal Jan de la Llosa.<\/p>\n<p><strong>Bitte fahre Sie nach Viliella und von dort nach Cal Jan, Google Maps usw. geben manchmal falsche Informationen an!<\/strong><\/p>\n<p>Parken auf dem Bauernhof (Parkgeb\u00fchr 4 \u20ac \/ d)<\/p>\n","accommodation":[{"hotel_name":"Refugi Cap de Rec","featured_image":"1394","telephone":"0034 973 29 31 00","contact_email":"estacio@lles.net","price":"72.50","location":"Cap de Rec (Lles)","stay_duration":"1. NACHT: EINE NACHT","website":"https:\/\/www.lles.net"},{"hotel_name":"Refugi Estany de la Pera","featured_image":"1395","telephone":"0034 606 991 473  ","contact_email":"estanysdelapera.refugi@feec.cat","price":"16,50 (pro Person zum Fr\u00fchst\u00fcck)","location":"Estany de la Pera (Lles)","stay_duration":"2. (3.): EIN ODER ZWEI N\u00c4CHTE  ","website":"https:\/\/www.estanysdelapera.cat"},{"hotel_name":"Hostal Pas de la Pera","featured_image":"1396","telephone":"+34 973 51 50 01","contact_email":"reserves@pasdelapera","location":"Aransa","stay_duration":"Eine Nacht","website":"https:\/\/cerdanya.org\/es\/allotjament\/hostal-pas-de-la-pera\/"},{"hotel_name":"Fonda Cal Abel","featured_image":"1590","telephone":"+34 619 641 692","contact_email":"fondacalabel@gmail.com","price":"70\u20ac Doppelzimmer","location":"Lles de Cerdanya","website":"https:\/\/www.fondacalabel.com"}],"map_iframe_url":"https:\/\/www.google.com\/maps\/d\/embed?mid=15tfvPBu_e01cIr_SfVvaQZdIxD6wl1w&ehbc"},"_links":{"self":[{"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/route\/2268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/route"}],"about":[{"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/types\/route"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/media\/2273"}],"wp:attachment":[{"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/media?parent=2268"}],"wp:term":[{"taxonomy":"best-season","embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/best-season?post=2268"},{"taxonomy":"camp-setup","embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/camp-setup?post=2268"},{"taxonomy":"difficulty-level","embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/difficulty-level?post=2268"},{"taxonomy":"trail-length","embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/trail-length?post=2268"},{"taxonomy":"trek-style","embeddable":true,"href":"https:\/\/burrotrek.com\/de\/wp-json\/wp\/v2\/trek-style?post=2268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}